{"id":62264,"date":"2023-03-28T09:30:08","date_gmt":"2023-03-28T07:30:08","guid":{"rendered":"https:\/\/homs-univ.edu.sy\/2023\/03\/une-soutenance-d-un-memoire-de-master-a-lafaculte-des-lettres-et-des-sciences-humaines\/"},"modified":"2023-03-28T09:30:08","modified_gmt":"2023-03-28T07:30:08","slug":"une-soutenance-d-un-memoire-de-master-a-lafaculte-des-lettres-et-des-sciences-humaines","status":"publish","type":"post","link":"https:\/\/homs-univ.edu.sy\/fr\/2023\/03\/une-soutenance-d-un-memoire-de-master-a-lafaculte-des-lettres-et-des-sciences-humaines\/","title":{"rendered":"La chercheuse Ghalia Mohammad Janoudi a obtenu le grade de master en langue arabe avec la mention \u00ab\u00a0Tr\u00e8s bien\u00a0\u00bb"},"content":{"rendered":"<p>La chercheuse Ghalia Mohammad Janoudi, de la Facult\u00e9 des Lettres et des Sciences Humaines, a soutenu son m\u00e9moire de master sous le th\u00e8me: \u00ab\u00a0Une explication d&rsquo;Al-Kafiya en grammaire par Shihab Al-Din Al-Dawlat Abadi Al-Hindi, une \u00e9tude et une enqu\u00eate\u00a0\u00bb sous l&rsquo;encadrement du Prof. Essam Koussa.<\/p>\n<p>Le jury a \u00e9t\u00e9 compos\u00e9 des membres suivants: Prof. Nabil Abou Amsha, en tant que pr\u00e9sident et membre, Prof. Essam Koussa, en tant qu&rsquo;encadreur, et Prof. Sanaa Al Rayes, en tant que membre.<\/p>\n<p>.<\/p>\n<p>A la fin de son expos\u00e9, le jury a d\u00e9cern\u00e9 le grade de master en langue arabe \u00e0 la chercheuse Ghalia Mohammad Janoudi avec la mention \u00ab\u00a0Tr\u00e8s bien\u00a0\u00bb et la note de 83.75%<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La chercheuse Ghalia Mohammad Janoudi, de la Facult\u00e9 des Lettres et des Sciences Humaines, a soutenu son m\u00e9moire de master sous le th\u00e8me: \u00ab\u00a0Une explication d&rsquo;Al-Kafiya<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":4,"featured_media":62205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[114],"tags":[],"class_list":["post-62264","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-theses-de-maitrise-et-de-doctorat"],"acf":[],"_links":{"self":[{"href":"https:\/\/homs-univ.edu.sy\/fr\/wp-json\/wp\/v2\/posts\/62264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homs-univ.edu.sy\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/homs-univ.edu.sy\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/homs-univ.edu.sy\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/homs-univ.edu.sy\/fr\/wp-json\/wp\/v2\/comments?post=62264"}],"version-history":[{"count":0,"href":"https:\/\/homs-univ.edu.sy\/fr\/wp-json\/wp\/v2\/posts\/62264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/homs-univ.edu.sy\/fr\/wp-json\/wp\/v2\/media\/62205"}],"wp:attachment":[{"href":"https:\/\/homs-univ.edu.sy\/fr\/wp-json\/wp\/v2\/media?parent=62264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/homs-univ.edu.sy\/fr\/wp-json\/wp\/v2\/categories?post=62264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/homs-univ.edu.sy\/fr\/wp-json\/wp\/v2\/tags?post=62264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}